{"id":208,"date":"2017-10-27T15:17:23","date_gmt":"2017-10-27T18:17:23","guid":{"rendered":"https:\/\/lastmarketplace.com\/store\/?page_id=208"},"modified":"2017-10-27T15:17:23","modified_gmt":"2017-10-27T18:17:23","slug":"terminos-y-condiciones","status":"publish","type":"page","link":"https:\/\/lastmarketplace.com\/store\/terminos-y-condiciones\/","title":{"rendered":"Terminos y Condiciones"},"content":{"rendered":"<p>MECANICA DEL SITIO:\u00a0 onemarketplace.com<\/p>\n<ol>\n<li>El sitio permite el Registro de Vendedores de productos y\/o servicios<\/li>\n<li>Cada vendedor sera cargado por el sitio sobre el 20% del precio final de sus ventas<\/li>\n<li>el 20% retenido sera utilizado como ingreso\u00a0 a repartir entre quienes ese periodo (mes) no obtuvieron ingresos de su tienda [valor Solidaridad]<\/li>\n<li>el sitio dara detalle electronico de ingresos percibidos por el 20% de comisiones, sin embargo, por cargos en pagos y transferencias, este valor se vera disminuido del teorico inicial, cosa que se reflejara en las transacciones electronicas asociadas, tanto en Paypal.com como en el BROU (hay tasas de servicios tanto en Paypal como en el banco receptor de fondos del exterior)<\/li>\n<li><\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MECANICA DEL SITIO:\u00a0 onemarketplace.com El sitio permite el Registro de Vendedores de productos y\/o servicios Cada vendedor sera cargado por el sitio sobre el 20% del precio final de sus ventas el 20% retenido sera utilizado como ingreso\u00a0 a repartir entre quienes ese periodo (mes) no obtuvieron ingresos de su tienda [valor Solidaridad] el sitio [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-208","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/lastmarketplace.com\/store\/wp-json\/wp\/v2\/pages\/208","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lastmarketplace.com\/store\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lastmarketplace.com\/store\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lastmarketplace.com\/store\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lastmarketplace.com\/store\/wp-json\/wp\/v2\/comments?post=208"}],"version-history":[{"count":1,"href":"https:\/\/lastmarketplace.com\/store\/wp-json\/wp\/v2\/pages\/208\/revisions"}],"predecessor-version":[{"id":209,"href":"https:\/\/lastmarketplace.com\/store\/wp-json\/wp\/v2\/pages\/208\/revisions\/209"}],"wp:attachment":[{"href":"https:\/\/lastmarketplace.com\/store\/wp-json\/wp\/v2\/media?parent=208"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}